{"id":37315,"date":"2025-08-20T14:19:36","date_gmt":"2025-08-20T12:19:36","guid":{"rendered":"https:\/\/www.villaggiosanfrancesco.com\/offer\/camping-flash-offer\/"},"modified":"2025-08-21T15:39:39","modified_gmt":"2025-08-21T13:39:39","slug":"camping-flash-offer","status":"publish","type":"offer","link":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/","title":{"rendered":"Camping Flash Offer"},"content":{"rendered":"<div  class=\"grids-section grids-is-advanced alignfull\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:3\/11;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>Erlebe den Sommer zwischen Meer und Pinienwald mit 10 % Rabatt<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-center\">Stell dir den Sonnenaufgang im Pinienwald vor, das Rauschen des Meeres und wie die Zeit langsamer vergeht.<br>Lass dich von der Freiheit leiten und genie\u00dfe das echte Vergn\u00fcgen eines Open-Air-Urlaubs:<br><strong><span style=\"font-size:22px;\">mit unserem Camping Flash Offer erh\u00e4ltst du 10 % Rabatt auf deinen Stellplatz<\/span><\/strong><br><strong><span style=\"font-size:22px;\">f\u00fcr Aufenthalte vom 6. September bis zum 6. Oktober ab 5 N\u00e4chten!<\/span><\/strong><br><br><em>Das Angebot ist g\u00fcltig vom <strong>22. August bis 6. September 2025<\/strong>, solange der Vorrat reicht.<br><\/em><br>Mit unserem <strong>Camping Flash Offer<\/strong> war ein Urlaub inmitten der Natur noch nie so greifbar nah.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/booking.villaggiosanfrancesco.com\/book\/offer\/sales?layout=10018842&amp;lang=de&amp;currency=EUR&amp;nsid=8791987d-5c34-4491-bd88-b43578bb6611\" target=\"_blank\" rel=\"noreferrer noopener\">Sichere dir den besten Preis<\/a><\/div>\n<\/div>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:1\/3;--_ga-row:1\/3;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:none;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:none;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img style=\"background-color: #3c41;\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10.webp\" alt=\"\" class=\"wp-image-37201\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10.webp 1024w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10-300x300.webp 300w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10-150x150.webp 150w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10-768x768.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:11\/13;--_ga-row:1\/3;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:none;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:none;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img style=\"background-color: #3c41;\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10.webp\" alt=\"\" class=\"wp-image-37201\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10.webp 1024w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10-300x300.webp 300w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10-150x150.webp 150w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/10-768x768.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<\/div>\n<\/div><\/div>\n\n<div  id=\"dettagli\" class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:#eafdff none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:#eafdff none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:#eafdff none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:2\/7;--_ga-row:2\/7;--_ga-va:center;--_ga-m-desktop:50px 0 50px 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:50px 0 50px 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:10px 0 10px 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h2 class=\"wp-block-heading\"><strong>Camping Flash Offer<\/strong><\/h2>\n\n\n\n<p>\ud83d\udc49 <strong>10 % Rabatt auf deinen Stellplatz<\/strong> f\u00fcr Aufenthalte von <strong>mindestens 5 N\u00e4chten<\/strong><br>\u23f0 G\u00fcltig vom <strong>22. August bis 6. September 2025<\/strong> (solange der Vorrat reicht)<br><br>Beende den Sommer mit Entspannung und Freiheit: Nutze das Angebot jetzt, denn es ist <strong>zeitlich begrenzt<\/strong>!<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Was ist inbegriffen \ud83c\udfd5\ufe0f<\/strong><\/h2>\n\n\n\n<p><strong>\u2705 Zugeteilter Stellplatz mit 1 Auto + 1 Campingunterkunft<br>\u2705 Alle Verbrauchskosten<br>\u2705 Alle mitreisenden Personen<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/booking.villaggiosanfrancesco.com\/book\/offer\/sales?layout=10018842&amp;lang=de&amp;currency=EUR&amp;nsid=8791987d-5c34-4491-bd88-b43578bb6611\" target=\"_blank\" rel=\"noreferrer noopener\">Jetzt buchen<\/a><\/div>\n<\/div>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:7\/12;--_ga-row:3\/6;--_ga-m-desktop:50px 0 50px 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:50px 0 50px 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:10px 0 10px 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"576\" height=\"586\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzolax576.webp\" alt=\"\" class=\"wp-image-37293\" style=\"background-color: #6b8570; object-fit:cover\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzolax576.webp 576w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzolax576-295x300.webp 295w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n<\/div>\n<\/div><\/div>\n\n<div  class=\"grids-section bottone-no-display grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:none;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:none;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:none;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\t<div id=\"boxTextSlider_2\" class=\"box-text-slider-container-wrapper  \" style=\"background-image: url(https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2023\/01\/panoramica-piazzole-camping-san-francesco-a-caorle.jpg);--box-text-bck-color: #f3f3f3;--box-text-color: #000000;\">\n\n\t\t<div class=\"box-text-slider_content\">\n\t\t\t<h2 class=\"wp-block-heading\"><strong>L\u2019OFFERTA<\/strong><\/h2>\n<p>\ud83d\udc49 <strong>-10% sulla tua piazzola<\/strong> per soggiorni di <strong>almeno 5 notti<\/strong><br \/>\n\u23f0 Valida dal <strong>22 agosto al 6 settembre 2025<\/strong> (fino a esaurimento disponibilit\u00e0)<br \/>\nConcludi l\u2019estate all\u2019insegna del relax e della libert\u00e0: approfittane subito perch\u00e9 questa offerta \u00e8 a <strong>tempo limitato<\/strong>!<\/p>\n<div class=\"wp-block-spacer\" style=\"height: 50px;\" aria-hidden=\"true\"><\/div>\n<h2 class=\"wp-block-heading\"><strong>Cosa \u00e8 incluso \ud83c\udfd5\ufe0f<\/strong><\/h2>\n<p>\u2705 Piazzola assegnata con 1 auto + 1 struttura da campeggio<br \/>\n\u2705 Tutti i consumi<br \/>\n\u2705 Tutte le persone che viaggiano con te<\/p>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"box-text-slider_slider\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-text-slider_slider_slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"full-width\" style=\"background-color: #5f6558;\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2023\/01\/tenda-in-piazzola-san-francesco.jpg\" alt=\"\" title=\"tenda in piazzola san francesco\" \/>\n\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-text-slider_slider_slide_title\">\n\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\n<\/div>\n<\/div><\/div>\n\n<div  class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:#d3fbff none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:none;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:#d3fbff none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:none;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:#d3fbff none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:none;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:3\/11;--_ga-row:1\/3;--_ga-m-desktop:50px 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:#d3fbff none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:50px 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:#d3fbff none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:50px 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:#d3fbff none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>Camping Flash offer<\/strong><\/h2>\n\n\n\n<p class=\"has-text-align-center\">Concludi l\u2019estate all\u2019insegna del relax e della libert\u00e0: approfittane subito perch\u00e9 questa offerta \u00e8 a <strong>tempo limitato<\/strong>!<br><br>\ud83d\udc49 <strong>-10% sulla tua piazzola<\/strong> per soggiorni di <strong>almeno 5 notti<\/strong><br>\u23f0 Valida dal <strong>22 agosto al 6 settembre 2025<\/strong> (fino a esaurimento disponibilit\u00e0)<\/p>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:3\/5;--_ga-row:4\/6;--_ga-va:center;--_ga-m-desktop:0 0 50px 0;--_ga-p-desktop:20px 20px 20px 20px;--_ga-bg-desktop:#00c6d8 none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 50px 0;--_ga-p-tablet:20px 20px 20px 20px;--_ga-bg-tablet:#00c6d8 none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 50px 0;--_ga-p-mobile:20px 20px 20px 20px;--_ga-bg-mobile:#00c6d8 none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"has-text-align-center\">Piazzola assegnata con 1 auto + 1 struttura da campeggio<\/p>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:6\/8;--_ga-row:4\/6;--_ga-va:center;--_ga-m-desktop:0 0 50px 0;--_ga-p-desktop:20px 20px 20px 20px;--_ga-bg-desktop:#00c6d8 none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 50px 0;--_ga-p-tablet:20px 20px 20px 20px;--_ga-bg-tablet:#00c6d8 none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 50px 0;--_ga-p-mobile:20px 20px 20px 20px;--_ga-bg-mobile:#00c6d8 none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"has-text-align-center\">Tutti i consumi<\/p>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:9\/11;--_ga-row:4\/6;--_ga-va:center;--_ga-m-desktop:0 0 50px 0;--_ga-p-desktop:20px 20px 20px 20px;--_ga-bg-desktop:#00c6d8 none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 50px 0;--_ga-p-tablet:20px 20px 20px 20px;--_ga-bg-tablet:#00c6d8 none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 50px 0;--_ga-p-mobile:20px 20px 20px 20px;--_ga-bg-mobile:#00c6d8 none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"has-text-align-center\">Tutte le persone che viaggiano con te<\/p>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:3\/11;--_ga-row:3\/4;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:30px 0 30px 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:30px 0 30px 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:30px 0 30px 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h2 class=\"wp-block-heading has-text-align-center\">Incluso nel prezzo<\/h2>\n\n<\/div>\n<\/div><\/div>\n\n<div  class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:20px 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:20px 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:20px 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:2\/12;--_ga-row:1\/7;--_ga-m-desktop:15px 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:15px 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:15px 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Jetzt buchen!<br>Diese Aktion endet am 6. September!<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center\">Ob mit <strong>Zelt, Wohnmobil oder Wohnwagen<\/strong> \u2013 dich erwartet ein Feriendorf mit:<br>&#8211; Einer einzigartigen Lage zwischen <strong>Meer und Pinienwald<\/strong><br>&#8211; <strong>Modernem Komfort<\/strong> f\u00fcr die ganze Familie<br>&#8211; Services und Aktivit\u00e4ten, die jeden Tag unvergesslich machen<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/booking.villaggiosanfrancesco.com\/book\/offer\/sales?layout=10018842&amp;lang=de&amp;currency=EUR&amp;nsid=8791987d-5c34-4491-bd88-b43578bb6611\" target=\"_blank\" rel=\"noreferrer noopener\">sichere dir den besten Preis<\/a><\/div>\n<\/div>\n\n<\/div>\n<\/div><\/div>\n\n<div  class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/4;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img style=\"background-color: #5b7048;\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.6.webp\" alt=\"\" class=\"wp-image-37271\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.6.webp 800w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.6-300x300.webp 300w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.6-150x150.webp 150w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.6-768x768.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:4\/7;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img style=\"background-color: #838169;\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.5.webp\" alt=\"\" class=\"wp-image-37266\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.5.webp 800w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.5-300x300.webp 300w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.5-150x150.webp 150w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.5-768x768.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:7\/10;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img style=\"background-color: #4e5b49;\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.3.webp\" alt=\"\" class=\"wp-image-37256\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.3.webp 800w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.3-300x300.webp 300w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.3-150x150.webp 150w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.3-768x768.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:10\/13;--_ga-row:1\/2;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full\"><img style=\"background-color: #828a65;\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.1.webp\" alt=\"\" class=\"wp-image-37246\" srcset=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.1.webp 800w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.1-300x300.webp 300w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.1-150x150.webp 150w, https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/piazzola800X800.1-768x768.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Erlebe den Sommer zwischen Meer und Pinienwald mit 10 % Rabatt<\/p>\n","protected":false},"author":29,"featured_media":37195,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"offer_categories":[],"class_list":["post-37315","offer","type-offer","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Camping Flash Offer - Villaggio San Francesco<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camping Flash Offer - Villaggio San Francesco\" \/>\n<meta property=\"og:description\" content=\"Erlebe den Sommer zwischen Meer und Pinienwald mit 10 % Rabatt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/\" \/>\n<meta property=\"og:site_name\" content=\"Villaggio San Francesco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VillaggioSanFrancesco\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T13:39:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1824\" \/>\n\t<meta property=\"og:image:height\" content=\"1216\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/\",\"url\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/\",\"name\":\"Camping Flash Offer - Villaggio San Francesco\",\"isPartOf\":{\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp\",\"datePublished\":\"2025-08-20T12:19:36+00:00\",\"dateModified\":\"2025-08-21T13:39:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#primaryimage\",\"url\":\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp\",\"contentUrl\":\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp\",\"width\":1824,\"height\":1216},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camping Flash Offer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/#website\",\"url\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/\",\"name\":\"Villaggio San Francesco\",\"description\":\"Caorle, VENEZIA\",\"publisher\":{\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/#organization\",\"name\":\"Villaggio San Francesco\",\"url\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2023\/03\/Logo-Villaggio-San-Francesco-Caorle-1.png\",\"contentUrl\":\"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2023\/03\/Logo-Villaggio-San-Francesco-Caorle-1.png\",\"width\":1206,\"height\":356,\"caption\":\"Villaggio San Francesco\"},\"image\":{\"@id\":\"https:\/\/www.villaggiosanfrancesco.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/VillaggioSanFrancesco\/\",\"https:\/\/www.instagram.com\/villaggiosanfrancesco\/\",\"https:\/\/www.youtube.com\/channel\/UClXJoJulrb1UANfZodeHn-g\",\"https:\/\/www.tiktok.com\/@sanfrancescoresort\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camping Flash Offer - Villaggio San Francesco","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Camping Flash Offer - Villaggio San Francesco","og_description":"Erlebe den Sommer zwischen Meer und Pinienwald mit 10 % Rabatt","og_url":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/","og_site_name":"Villaggio San Francesco","article_publisher":"https:\/\/www.facebook.com\/VillaggioSanFrancesco\/","article_modified_time":"2025-08-21T13:39:39+00:00","og_image":[{"width":1824,"height":1216,"url":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/","url":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/","name":"Camping Flash Offer - Villaggio San Francesco","isPartOf":{"@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#primaryimage"},"image":{"@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp","datePublished":"2025-08-20T12:19:36+00:00","dateModified":"2025-08-21T13:39:39+00:00","breadcrumb":{"@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#primaryimage","url":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp","contentUrl":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931.webp","width":1824,"height":1216},{"@type":"BreadcrumbList","@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/offer\/camping-flash-offer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.villaggiosanfrancesco.com\/de\/"},{"@type":"ListItem","position":2,"name":"Camping Flash Offer"}]},{"@type":"WebSite","@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/#website","url":"https:\/\/www.villaggiosanfrancesco.com\/de\/","name":"Villaggio San Francesco","description":"Caorle, VENEZIA","publisher":{"@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.villaggiosanfrancesco.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/#organization","name":"Villaggio San Francesco","url":"https:\/\/www.villaggiosanfrancesco.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2023\/03\/Logo-Villaggio-San-Francesco-Caorle-1.png","contentUrl":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2023\/03\/Logo-Villaggio-San-Francesco-Caorle-1.png","width":1206,"height":356,"caption":"Villaggio San Francesco"},"image":{"@id":"https:\/\/www.villaggiosanfrancesco.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VillaggioSanFrancesco\/","https:\/\/www.instagram.com\/villaggiosanfrancesco\/","https:\/\/www.youtube.com\/channel\/UClXJoJulrb1UANfZodeHn-g","https:\/\/www.tiktok.com\/@sanfrancescoresort"]}]}},"featured_img":"https:\/\/www.villaggiosanfrancesco.com\/wp-content\/uploads\/2025\/08\/ALE_3931-1568x1045.webp","coauthors":[],"author_meta":{"author_link":"https:\/\/www.villaggiosanfrancesco.com\/de\/news\/author\/mattia_fh8r4\/","display_name":"Mattia"},"relative_dates":{"created":"Posted 9\u00a0Monaten ago","modified":"Updated 9\u00a0Monaten ago"},"absolute_dates":{"created":"Posted on August 20, 2025","modified":"Updated on August 21, 2025"},"absolute_dates_time":{"created":"Posted on August 20, 2025 2:19 p.m.","modified":"Updated on August 21, 2025 3:39 p.m."},"featured_img_caption":"","tax_additional":{"offer_categories":{"linked":[],"unlinked":[],"slug":"offer_categories","name":"Kategorien"},"translation_priority":{"linked":["<a href=\"https:\/\/www.villaggiosanfrancesco.com\/de\/?taxonomy=translation_priority&#038;term=optional-de\" class=\"advgb-post-tax-term\">Optional<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Optional<\/span>"],"slug":"translation_priority","name":"\u00dcbersetzungspriorit\u00e4ten"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/offer\/37315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/offer"}],"about":[{"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/types\/offer"}],"author":[{"embeddable":true,"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/users\/29"}],"version-history":[{"count":0,"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/offer\/37315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/media\/37195"}],"wp:attachment":[{"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/media?parent=37315"}],"wp:term":[{"taxonomy":"offer_categories","embeddable":true,"href":"https:\/\/www.villaggiosanfrancesco.com\/de\/wp-json\/wp\/v2\/offer_categories?post=37315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}